{"id":6646,"date":"2025-12-22T09:46:00","date_gmt":"2025-12-22T08:46:00","guid":{"rendered":"http:\/\/www.interflora.fr\/blog\/?p=6646"},"modified":"2026-01-15T16:37:21","modified_gmt":"2026-01-15T15:37:21","slug":"la-rose","status":"publish","type":"post","link":"https:\/\/www.interflora.fr\/blog\/la-rose\/","title":{"rendered":"La rose, reine des fleurs"},"content":{"rendered":"\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0\"><strong>Depuis des mill\u00e9naires, la <a href=\"https:\/\/www.interflora.fr\/c\/roses?utm_source=texte&amp;utm_medium=magdeflora&amp;utm_campaign=fiche-fleur-la-rose\" target=\"_blank\" rel=\"noopener\">rose<\/a> fascine. De tous temps, les artistes ont vu en elle une source d\u2019inspiration in\u00e9puisable, un embl\u00e8me de l\u2019amour absolu, au point de la hisser au rang tr\u00e8s convoit\u00e9 de reine des fleurs. Les rosi\u00e9ristes ont su l\u2019apprivoiser et la doter d\u2019innombrables formes, couleurs et parfums pour notre plus grand bonheur. La rose enchante aujourd\u2019hui nos jardins avec son incroyable diversit\u00e9, et s\u2019offre en bouquet pour d\u00e9clamer nos plus nobles sentiments&#8230;<\/strong><\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:var(--wp--preset--spacing--20);padding-bottom:0;padding-left:var(--wp--preset--spacing--20);grid-template-columns:auto 27%\"><div class=\"wp-block-media-text__content\">\n<p><strong>La rose est le nom de la fleur du rosier, plante appartenant au genre Rosa et de la famille des Rosac\u00e9es<\/strong>.<br>La rose est l\u2019une des fleurs les plus cultiv\u00e9es au monde, et elle se place sans conteste sur la premi\u00e8re marche du podium des fleurs les plus vendues ! En fleur coup\u00e9e, c\u2019est la rose rouge qui est la plus sollicit\u00e9e, notamment en p\u00e9riode de <a href=\"https:\/\/www.interflora.fr\/c\/fleurs-saint-valentin?utm_source=texte&amp;utm_medium=magdeflora&amp;utm_campaign=fiche-fleur-la-rose\" target=\"_blank\" rel=\"noopener\">Saint-Valentin<\/a>. Et nos jardins ou balcons ne sont pas en reste avec un vaste choix de rosiers !<\/p>\n\n\n\n<p>A l&rsquo;origine de tous les rosiers, il y a les rosiers botaniques, ou rosiers sauvages, comprenant par exemple les \u00e9glantiers. Les botanistes ont recens\u00e9 entre 130 et 150 esp\u00e8ces. Les rosiers cultiv\u00e9s aujourd\u2019hui sont le r\u00e9sultat de plusieurs mill\u00e9naires de transformation. Les vari\u00e9t\u00e9s sont d\u00e9sormais innombrables, et l\u2019on estime que plus de 3000 cultivars sont disponibles aujourd\u2019hui dans le monde. Seule une douzaine d\u2019esp\u00e8ces ont \u00e9t\u00e9 utilis\u00e9es au d\u00e9part pour cr\u00e9er la plupart des rosiers cultiv\u00e9s que l\u2019on trouve aujourd\u2019hui.<\/p>\n\n\n\n<p>A l&rsquo;origine de tous les rosiers, il y a les rosiers botaniques, ou rosiers sauvages, comprenant par exemple les \u00e9glantiers. Les botanistes ont recens\u00e9 entre 130 et 150 esp\u00e8ces. Les rosiers cultiv\u00e9s aujourd\u2019hui sont le r\u00e9sultat de plusieurs mill\u00e9naires de transformation. Les vari\u00e9t\u00e9s sont d\u00e9sormais innombrables, et l\u2019on estime<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rose-black-beauty-.jpg\" alt=\"Rose noire\" class=\"wp-image-56993 size-full\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rose-black-beauty-.jpg 1000w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rose-black-beauty--300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rose-black-beauty--150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rose-black-beauty--768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<p>que plus de 3000 cultivars sont disponibles aujourd\u2019hui dans le monde. Seule une douzaine d\u2019esp\u00e8ces ont \u00e9t\u00e9 utilis\u00e9es au d\u00e9part pour cr\u00e9er la plupart des rosiers cultiv\u00e9s que l\u2019on trouve aujourd\u2019hui<\/p>\n\n\n\n<p><strong>Dans sa forme originelle, la rose a cinq p\u00e9tales et des \u00e9tamines bien visibles<\/strong>, semblable \u00e0 ce qu\u2019on appelle commun\u00e9ment l\u2019\u00e9glantier (<em>rosa canina<\/em>) qui est en r\u00e9alit\u00e9 un rosier sauvage. Cette tenue simple a s\u00e9duit nombre de botanistes, qui l\u2019ont rapport\u00e9 des quatre coins du monde pour la confier aux rosi\u00e9ristes. Ces derniers ont su cr\u00e9er au fil des si\u00e8cles de multiples vari\u00e9t\u00e9s. Gr\u00e2ce \u00e0 cette \u00e9tonnante diversit\u00e9, on trouve aujourd\u2019hui des roses offrant d\u2019innombrables teintes, nuances, tailles, inflorescences et formes : simples, semi-doubles ou doubles (dites aussi \u00ab pleines \u00bb), grimpantes, en buissons, et des p\u00e9riodes de floraison tr\u00e8s \u00e9tal\u00e9es.<br><strong>Le mot \u00ab\u00a0rose\u00a0\u00bb vient du latin <em>rosa<\/em>, <em>rosae<\/em>, qui d\u00e9signe \u00e0 la fois la fleur et le rosier lui-m\u00eame.<\/strong> Ce terme viendrait du grec ancien <em>rhodon<\/em>.<\/p>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rouge<\/span><p>36.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvdWdlLzAvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249M1JFUg==\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Tendresse<\/span><p>29.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3RlbmRyZXNzZS8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTFURU4=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rose<\/span><p>37.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvc2UvMC9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj0zUkVQ\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Grandes roses sur-mesure<\/span><p>59.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3Jvc2VzLWEtbGEtZm9saWUvNi9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj0xQUZP\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons alignwide is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.interflora.fr\/c\/roses-saint-valentin\">Livraison de roses pour la Saint Valentin<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Roses anciennes et roses modernes<\/h2>\n\n\n\n<p><strong>On distingue les \u00ab roses anciennes \u00bb des \u00ab&nbsp;roses modernes&nbsp;\u00bb<\/strong>. Les roses anciennes sont g\u00e9n\u00e9ralement les cultivars ant\u00e9rieurs \u00e0 1867, n\u00e9s des roses botaniques. Elles ont la caract\u00e9ristique de sentir divinement bon, de d\u00e9velopper une floraison abondante mais courte et non remontante. Si beaucoup ont \u00e9t\u00e9 perdues, certaines sont encore cultiv\u00e9es comme par exemple :<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--20);padding-bottom:0;padding-left:var(--wp--preset--spacing--20);grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/pink-roses.jpg\" alt=\"Rosier rose\" class=\"wp-image-46789 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<ul class=\"wp-block-list\">\n<li><strong>Les roses galliques<\/strong>, <em>Rosa gallica<\/em>, que l\u2019on peut traduire par \u00ab rose de France \u00bb. Cette esp\u00e8ce est en quelque sorte l\u2019anc\u00eatre de toutes les roses europ\u00e9ennes,<\/li>\n\n\n\n<li><strong>Les roses cent-feuilles<\/strong>, <em>Rosa centifolia<\/em>, nomm\u00e9es ainsi en raison de son grand nombre de p\u00e9tales,<\/li>\n\n\n\n<li><strong>Les roses de Damas<\/strong>, <em>Rosa damascena<\/em>, qui seraient venus du Moyen Orient. Tr\u00e8s parfum\u00e9s, elles sont encore cultiv\u00e9es en Bulgarie et au Maroc, pour la production d\u2019essence et d\u2019eau de rose.<\/li>\n\n\n\n<li><strong>Les rosiers alba<\/strong>, (qui signifie \u00ab blanc \u00bb), <em>Rosa x alba<\/em>, d\u00e9j\u00e0 signal\u00e9s chez les Grecs et les Romains, venus d\u2019Asie Mineure ou Centrale.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p><strong>En 1867, &lsquo;La France&rsquo;, premi\u00e8re hybride de th\u00e9, est cr\u00e9\u00e9e et marque la naissance des \u00ab\u00a0roses modernes\u00a0\u00bb<\/strong>. Ce terme regroupe toutes les vari\u00e9t\u00e9s obtenues apr\u00e8s cette date, comme les rosiers \u00ab\u00a0\u00e0 grandes fleurs\u00a0\u00bb, les \u00ab\u00a0floribunda\u00a0\u00bb &#8211; \u00e0 la floraison abondante &#8211; et les \u00ab\u00a0rosiers anglais\u00a0\u00bb.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\"><a name=\"histoire\"><\/a>Histoire de la rose<\/h2>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">La rose dans l&rsquo;Antiquit\u00e9<\/h3>\n\n\n\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">On sait que <strong>les Grecs et les H\u00e9breux appr\u00e9ciaient d\u00e9j\u00e0 la rose<\/strong>, notamment pour les c\u00e9r\u00e9monies nuptiales, et la cultivaient. Des <a href=\"https:\/\/www.interflora.fr\/c\/roses\">roses<\/a> ont \u00e9t\u00e9 \u00e9galement retrouv\u00e9es <strong>dans des tombeaux \u00e9gyptiens<\/strong>, dans le but d&rsquo;accompagner les morts vers l&rsquo;\u00e9ternit\u00e9.<\/p>\n\n\n\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>Les Romains, eux, d\u00e9velopp\u00e8rent une v\u00e9ritable passion pour cette fleur<\/strong> : ses p\u00e9tales jonchaient le sol et l\u2019on en r\u00e9pandait sur les invit\u00e9s les jours de f\u00eate. Les roses \u00e9taient cultiv\u00e9es principalement en Egypte ainsi qu\u2019en Perse (actuel Iran), c\u2019est pourquoi les Romains les import\u00e8rent d&rsquo;abord par bateaux entiers avant de les cultiver eux-m\u00eames. Ils d\u00e9velopp\u00e8rent pour cela un syst\u00e8me ing\u00e9nieux afin de forcer leur floraison, en r\u00e9chauffant les sols de culture \u00e0 l\u2019aide de canalisations d\u2019eau chaude. M\u00eame si peu d\u2019\u00e9crits l\u2019attestent, on suppose que la rose de cette \u00e9poque \u00e9tait la rose de Damas (<em>Rosa x damascena<\/em>), r\u00e9pandue ensuite dans le monde par les Romains au fur et \u00e0 mesure de leurs conqu\u00eates de nouveaux territoires.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"949\" height=\"954\" data-id=\"56995\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-multicolores.jpg\" alt=\"P\u00e9tales de roses multicolores\" class=\"wp-image-56995\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-multicolores.jpg 949w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-multicolores-298x300.jpg 298w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-multicolores-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-multicolores-768x772.jpg 768w\" sizes=\"auto, (max-width: 949px) 100vw, 949px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"645\" data-id=\"56994\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses.jpg\" alt=\"P\u00e9tales de roses multicolores\" class=\"wp-image-56994\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses.jpg 642w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/petales-roses-150x150.jpg 150w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">La rose au Moyen Age<\/h3>\n\n\n\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\"><strong>En France, au XIIIe si\u00e8cle, on cultivait d\u00e9j\u00e0 la rose \u00e0 Provins<\/strong> : on raconte que le comte de Champagne et roi de Navarre Thibaut IV, rapporta de son exp\u00e9dition \u00e0 J\u00e9rusalem une rose rouge tr\u00e8s parfum\u00e9e, aujourd\u2019hui appel\u00e9e <em>Rosa x gallica \u2018Officinalis\u2019<\/em>, plus commun\u00e9ment \u00ab rose de Provins \u00bb ou \u00ab rose des apothicaires \u00bb. Si sa culture se d\u00e9veloppa, c\u2019\u00e9tait alors surtout \u00e0 des fins m\u00e9dicinales, car on attribuait \u00e0 cette rose le pouvoir de gu\u00e9rir de nombreuses maladies. Bien que Charlemagne encourageait la plantation de rosiers pr\u00e8s des \u00e9difices religieux dans son capitulaire de villis, la rose \u00e9tait alors consid\u00e9r\u00e9e comme une fleur moins ornementale qu\u2019utilitaire.<\/p>\n\n\n\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">Les hybridations \u00e9taient jusque-l\u00e0 spontan\u00e9es. <strong>Ainsi au XVIIe si\u00e8cle, une mutation de <em>Rosa gallica<\/em> fit na\u00eetre les <em>Rosa centifolia<\/em> (\u00ab roses centfeuilles \u00bb), dont une mutation \u00e9galement au XVIIIe s\u00e8cle donna les \u00ab rosiers moussus \u00bb<\/strong>.<\/p>\n\n\n\n<p style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--20)\">&nbsp;Jusqu\u2019\u00e0 la fin du XVIIIe si\u00e8cle, on comptait seulement une trentaine d\u2019esp\u00e8ces de roses. Si les rosiers de l\u2019\u00e9poque se pr\u00eataient peu \u00e0 l\u2019aspect rigide des jardins dits \u00ab \u00e0 la fran\u00e7aise \u00bb, la mode du style anglais, plus naturel, arriva en France fin XVIIIe et lanca leur r\u00e9putation. Les aristocrates furent alors d\u00e9sireux de remanier les parcs de leurs propri\u00e9t\u00e9s avec de nouvelles plantes. Les p\u00e9pini\u00e9ristes suivirent le mouvement en proposant \u00e0 leur client\u00e8le <strong>des vari\u00e9t\u00e9s de roses de plus en plus nombreuses<\/strong>.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">L\u2019imp\u00e9ratrice Jos\u00e9phine et la passion des roses<\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/annesophiebenoit-interflora-saint-valentin-51-1-1024x1024.jpg\" alt=\"Femme avec des roses dans les mains\" class=\"wp-image-47295 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"padding-top:0;padding-right:var(--wp--preset--spacing--20);padding-bottom:0;padding-left:var(--wp--preset--spacing--20)\"><strong>Le fran\u00e7ais Jacques-Louis Descemet, premier obtenteur de roses, publia en 1803 un ouvrage sur ces fleurs<\/strong>. Il y recensa 80 rosiers, des rosiers botaniques mais aussi des roses galliques et centfeuilles. En 10 ans, il ajouta \u00e0 son catalogue environ 200 nouvelles vari\u00e9t\u00e9s. Un v\u00e9ritable int\u00e9r\u00eat se d\u00e9veloppa alors dans le pays autour de cette fleur, insuffl\u00e9 principalement par l\u2019<strong>imp\u00e9ratrice Jos\u00e9phine de Beauharnais<\/strong>. Entre 1803 et 1814, elle envoya des botanistes \u00e0 travers le monde pour enrichir la collection de sa roseraie de la Malmaison. <strong>Elle rassembla ainsi la plus incroyable des collections<\/strong>, de pr\u00e8s de 600 vari\u00e9t\u00e9s, qui constituera par la suite une vrai mine d\u2019or pour les p\u00e9pini\u00e9ristes.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">Les rosiers de Chine : premiers rosiers remontants<\/h3>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">Au d\u00e9but du XIXe si\u00e8cle, on hybrida \u00e0 une vitesse incroyable les roses galliques, de Damas et centfeuilles. Puis l\u2019<strong>on introduisit les rosiers de Chine<\/strong> (<em>Rosa chinensis<\/em>), qui avaient un atout in\u00e9dit \u00e0 l\u2019\u00e9poque : contrairement aux roses de l\u2019\u00e9poque, <strong>ils avaient la capacit\u00e9 de fleurir plusieurs fois par an<\/strong>. <strong>Cette introduction marqua un tournant dans la culture des rosiers<\/strong>, et les p\u00e9pini\u00e9ristes fran\u00e7ais s\u2019attel\u00e8rent \u00e0 croiser ces rosiers de Chine avec les rosiers existants, obtenant ainsi des centaines de nouveaux hybrides \u00e0 <strong>floraison dite \u00ab\u00a0remontante\u00a0\u00bb<\/strong>. Les anciennes vari\u00e9t\u00e9s \u00e0 floraison unique furent alors peu \u00e0 peu d\u00e9laiss\u00e9es.<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">Parmi les rosiers chinois les plus remarqu\u00e9s, on compte surtout <strong>les rosiers th\u00e9<\/strong>, avec leurs p\u00e9tales semblables \u00e0 de la soie, aux couleurs tr\u00e8s d\u00e9licates. Leurs exigences climatiques, notamment leur besoin de chaleur, amen\u00e8rent sa culture \u00e0 se d\u00e9velopper autour du bassin m\u00e9diterran\u00e9en. Gilbert Nabonnaud, install\u00e9 \u00e0 Golfe-Juan en fit sa sp\u00e9cialit\u00e9, et d\u00e9veloppa pr\u00e8s de 200 vari\u00e9t\u00e9s qui firent fureur chez les aristocrates de la r\u00e9gion. <strong>Parall\u00e8lement, la culture sous serre et le commerce de la fleur coup\u00e9e se d\u00e9veloppa notamment gr\u00e2ce \u00e0 l\u2019arriv\u00e9e du chemin de fer<\/strong>. On put ainsi acheminer facilement et toute l\u2019ann\u00e9e des fleurs vers la capitale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Des roses et des c\u00e9l\u00e9brit\u00e9s<\/h2>\n\n\n\n<p>Ecrivains, chanteurs, acteurs, hommes politiques\u2026 Les rosi\u00e9ristes ont rendu hommage \u00e0 de nombreuses personnalit\u00e9s de tous bords ! Citons par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rose \u2018Charles Aznavour\u2019 (Meilland)<\/li>\n\n\n\n<li>Rose \u2018Maria Callas\u2019 (Meilland)<\/li>\n\n\n\n<li>Rose \u2018Catherine Deneuve\u2019 (Meilland)<\/li>\n\n\n\n<li>Rose \u2018Queen Elizabeth\u2019 (Lammerts)<\/li>\n\n\n\n<li>Rose \u2018Louis de Fun\u00e8s\u2019 (Meilland)<\/li>\n\n\n\n<li>Rose \u2018Honor\u00e9 de Balzac\u2019 (Meilland)<\/li>\n\n\n\n<li>Rose \u2018Henri Matisse\u2019 (Delbard)<\/li>\n\n\n\n<li>Rose \u2018Alain Souchon\u2019 (Meilland)<\/li>\n<\/ul>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rose<\/span><p>37.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvc2UvMC9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj0zUkVQ\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rouge<\/span><p>36.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvdWdlLzAvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249M1JFUg==\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Roses signature LEGO\u00ae<\/span><p>87.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3Jvc2VzLXNpZ25hdHVyZS1sZWdvLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249QkVQMjVMR1I=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Ecrin de roses<\/span><p>42.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2VjcmluLWRlLXJvc2VzLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249M0VS\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons alignwide is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.interflora.fr\/c\/roses-saint-valentin\">Livraison de roses pour la Saint Valentin<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">La naissance des roses modernes<\/h3>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Lyon, ville tr\u00e8s prosp\u00e8re, devint la capitale internationale de la rose, et de nombreuses vari\u00e9t\u00e9s y virent le jour entre 1870 et 1914.<\/strong><br>La c\u00e9l\u00e8bre \u2018La France\u2019, obtenue en 1867 par Jean-Baptiste Guillot fils, marqua un tournant dans l\u2019histoire de la rose. Associant la force des hybrides remontants \u00e0 la beaut\u00e9 des rosiers th\u00e9, elle engendra <strong>l\u2019apparition d\u2019une nouvelle famille, celle des hybrides de th\u00e9<\/strong>, anc\u00eatre de la majorit\u00e9 des roses \u00e0 grandes fleurs modernes. Cette vari\u00e9t\u00e9 cr\u00e9a un grand changement : <strong>on d\u00e9cida officiellement que toutes les vari\u00e9t\u00e9s de roses qui existaient avant cette date de 1867 seraient appel\u00e9es \u00ab roses anciennes \u00bb, et les suivantes dont les hybrides de th\u00e9 \u00ab roses modernes \u00bb<\/strong>. N\u00e9anmoins, certaines roses dites \u00ab&nbsp;modernes&nbsp;\u00bb correspondent si bien aux caract\u00e9ristiques des anciennes qu\u2019elles sont consid\u00e9r\u00e9es comme telles.<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Au XXe si\u00e8cle se d\u00e9veloppa un v\u00e9ritable engouement pour les hybrides de th\u00e9<\/strong>, rosiers buissons \u00e0 grandes fleurs, avec les cr\u00e9ations de <strong>Georges Delbard ou encore de Meilland<\/strong>. Puis <strong>le rosi\u00e9riste anglais David Austin, cr\u00e9a les \u00ab roses anglaises \u00bb<\/strong> en croisant des roses anciennes avec des roses modernes, donnant ainsi \u00ab des roses nouvelles dans la tradition des anciennes \u00bb. Il relanca la mode de l\u2019aspect des roses anciennes, aux allures plus sauvages, et aux parfums plus prononc\u00e9s. Encore aujourd\u2019hui, les p\u00e9pini\u00e8res puisent \u00e0 nouveau dans les roses anciennes pour donner aux roses modernes des allures d\u2019antan.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">La rose, fleur de l\u00e9gendes<\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">De tous temps, la reine des fleurs a \u00e9merveill\u00e9 les hommes. <strong>Dans la mythologie grecque, on attribue la naissance de la rose \u00e0 Chloris<\/strong> (Flore chez les Romains), d\u00e9esse des fleurs. Chloris se promenait lorsqu\u2019elle trouva le corps sans vie d\u2019une nymphe pour laquelle elle avait beaucoup d\u2019affection. Afin de faire d\u2019elle la plus belle fleur, elle la m\u00e9tamorphosa en une rose et demanda aux autres dieux d\u2019enrichir sa cr\u00e9ation de leurs pouvoirs : Aphrodite lui accorda la beaut\u00e9 \u00e9ternelle, Dionysos la baigna dans un nectar pour lui r\u00e9v\u00e9ler le plus doux des parfums et enfin les Trois Gr\u00e2ces ajout\u00e8rent la joie, le charme et l\u2019\u00e9clat\u2026<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><strong>Chez les Romains existe une autre version<\/strong> : un arbuste \u00e9pineux aurait retard\u00e9 la course d\u2019une nymphe qui tentait d\u2019\u00e9chapper \u00e0 Bacchus, en s\u2019accrochant \u00e0 son voile. Bacchus, reconnaissant d\u2019avoir pu capturer sa proie, remercia l\u2019arbuste en le dotant de splendides fleurs odorantes.<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><strong>La rose rouge est rattach\u00e9e \u00e0 V\u00e9nus<\/strong> (\u00e9quivalente de la Grecque Aphrodite), d\u00e9esse romaine de l\u2019amour et de la beaut\u00e9, mais les versions divergent. La d\u00e9esse se serait bless\u00e9e avec l\u2019\u00e9pine d\u2019une rose blanche, transformant ainsi la fleur en rose rouge. On raconte aussi que la rose se serait empourpr\u00e9e lorsque son fils Cupidon renversa son verre de vin sur elle.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1344\" height=\"467\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2023\/12\/roses-rouges.jpg\" alt=\"Bouquet de roses rouges\" class=\"wp-image-56929\" style=\"aspect-ratio:1;object-fit:cover;width:360px;height:auto\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2023\/12\/roses-rouges.jpg 1344w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2023\/12\/roses-rouges-300x104.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2023\/12\/roses-rouges-1024x356.jpg 1024w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2023\/12\/roses-rouges-768x267.jpg 768w\" sizes=\"auto, (max-width: 1344px) 100vw, 1344px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Dans la religion chr\u00e9tienne, la rose est riche de symboles<\/strong> : elle y est \u00e0 la fois l\u2019expression du martyre et du sang du Christ, et la rose blanche la repr\u00e9sentation de la Vierge Marie.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\"><a name=\"arts\"><\/a>La rose, les Arts et les Lettres<\/h2>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">La rose dans les Lettres<\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/brassee-roses-blanches.jpg\" alt=\"Brass\u00e9e de roses blanches\" class=\"wp-image-56996 size-full\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/brassee-roses-blanches.jpg 1000w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/brassee-roses-blanches-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/brassee-roses-blanches-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/brassee-roses-blanches-768x768.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Le persan Saadi, la Grecque Sappho, Shakespeare, Apollinaire, Verlaine, Anna de Noailles, Rilke, Garcia Lorca\u2026 les po\u00e8tes ont tous c\u00e9l\u00e9br\u00e9 au fil des si\u00e8cles la beaut\u00e9 d\u00e9licate de la fleur, m\u00e9taphore de l\u2019\u00eatre aim\u00e9 mais aussi du temps qui passe.<\/p>\n\n\n\n<p>On retrouve d\u00e9j\u00e0 des \u00e9vocations de la rose dans <strong><em>l\u2019Iliade<\/em> et <em>L\u2019Odyss\u00e9e<\/em> du Grec Hom\u00e8re<\/strong>. Elle est aussi pr\u00e9sente dans <strong><em>Les M\u00e9tamorphoses<\/em> d\u2019Ovide<\/strong>, qui l\u2019associe \u00e0 la d\u00e9esse Aurore, ainsi que dans l\u2019\u0153uvre de Sappho puis d\u2019Achille Tatius qui dit d\u2019elle <em>\u00ab Si Zeus avait voulu donner aux fleurs un roi, c\u2019est la rose qui r\u00e8gnerait sur les fleurs. Elle est la parure de la terre, la gloire des plantes ; elle est l\u2019\u0153il des fleurs, la rougeur de la prairie : c\u2019est la beaut\u00e9 dans tout son \u00e9clat ; elle respire l\u2019amour, elle est messag\u00e8re d\u2019Aphrodite \u00bb<\/em> (<em>Le roman de Leucipp\u00e9 et Clitophon<\/em>, IIe-IIIe si\u00e8cle). Attribut de la d\u00e9esse Aphrodite, la rose est alors d\u00e9j\u00e0 le symbole de l\u2019amour et de la beaut\u00e9.<\/p>\n\n\n\n<p><strong><em>Le Roman de la Rose<\/em><\/strong>, \u00e9crit par Guillaume de Loris vers 1230 et poursuivi par Jean de Meung, constitue l\u2019\u0153uvre la plus c\u00e9l\u00e8bre du Moyen Age. Dans ce po\u00e8me all\u00e9gorique, la rose est l\u2019objet de toutes les qu\u00eates, le symbole de l\u2019\u00eatre aim\u00e9.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><strong>Dans la po\u00e9sie de Ronsard<\/strong>, au XVIe si\u00e8cle, <strong>la rose repr\u00e9sente la fragilit\u00e9 de la vie<\/strong>, notamment dans son c\u00e9l\u00e8bre po\u00e8me \u00ab\u00a0Ode \u00e0 Cassandre\u00a0\u00bb (<em>\u00ab Mignonne, allons voir si la rose.. \u00bb<\/em>). <strong>Idem chez Corneille ou Fran\u00e7ois de Malherbe, o\u00f9 la fleur est le t\u00e9moignage du temps qui passe et de la beaut\u00e9 \u00e9ph\u00e9m\u00e8re<\/strong>. Cette th\u00e9matique de la fragilit\u00e9 sera reprise plus tard par Victor Hugo, dans <em>La rose de l\u2019Infante<\/em>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading alignwide\">La rose dans les Arts<\/h3>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><strong>La premi\u00e8re repr\u00e9sentation de roses peintes est d\u00e9couverte en 1900 dans les vestiges du palais de Cnossos<\/strong> en Cr\u00eate&nbsp;: sur \u00ab\u00a0la fresque \u00e0 l\u2019oiseau bleu\u00a0\u00bb, datant de l\u2019an 2000 avant J.-C., on peut voir des rosiers fleuris. La rose est \u00e9galement repr\u00e9sent\u00e9e sur des pi\u00e8ces de monnaie datant de 500 avant J.-C., retrouv\u00e9es sur l\u2019\u00eele grecque de Rhodes. Chez les Grecs comme chez les Romains, on sait que des repr\u00e9sentations de la rose ornaient, comme beaucoup de fleurs, les b\u00e2timents.<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">Tout comme dans le domaine des Lettres, la rose en peinture est souvent la repr\u00e9sentation de l\u2019amour, mais aussi de la fragilit\u00e9 de la vie et des sentiments. Dans la religion chr\u00e9tienne, la rose \u00e9voque l\u2019amour universel et pur, et de ce fait la Vierge Marie. On sait pourtant qu\u2019au d\u00e9but de l\u2019\u00e8re chr\u00e9tienne, les P\u00e8res de l\u2019Eglise (Cl\u00e9ment d\u2019Alexandrie, Tertullien) interdirent la repr\u00e9sentation de fleurs dans l\u2019iconographie religieuse. Cet interdit fut plus tard lev\u00e9 pour la rose par Saint Paulin de Nola.<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Pierre-Joseph Redout\u00e9 (1759-1840), cr\u00e9e son fameux ouvrage <em>Les Roses<\/em>, planches en eau-forte en pointill\u00e9 colori\u00e9e, illustrant les textes du rosi\u00e9riste Claude-Antoine Thory.<\/strong> Il s\u2019inspire pour ses aquarelles &#8211; d\u2019une minutie presque botanique &#8211; de la collection de la Malmaison de l\u2019Imp\u00e9ratrice Jos\u00e9phine, dont il est le peintre officiel.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-full\" style=\"margin-right:0;margin-left:0\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/rosa-centelia.jpg\" alt=\"Rose de centifolia avec des feuilles\" class=\"wp-image-46960\"\/><figcaption class=\"wp-element-caption\">Rosa \u00d7centifolia (rosier centfeuilles), de <br>Pierre-Joseph Redout\u00e9.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\"><strong><strong>D\u2019innombrables peintres, de toutes \u00e9poques confondues, ont puis\u00e9 l\u2019inspiration dans la rose.<\/strong><\/strong> Citons parmi eux Sandro Botticelli et sa <em>Naissance de V\u00e9nus<\/em> (1485), Vincent Van Gogh et ses <em>Rosiers en fleurs<\/em> (1889), et chez les impressionnistes Edouard Manet et son tableau <em>Roses dans un verre de champagne<\/em> (1881), Pierre-Auguste Renoir avec <em>Roses et jasmin dans un vase de Delft<\/em> (1881) ou encore Claude Monet et <em>Le Rosier<\/em>. La rose est \u00e9galement tr\u00e8s pr\u00e9sente dans les natures mortes des peintres flamands et hollandais du XVIIe si\u00e8cle.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/02\/BEP25LGR-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Roses signature LEGO\u00ae<\/span><p>87.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3Jvc2VzLXNpZ25hdHVyZS1sZWdvLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249QkVQMjVMR1I=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Amour exceptionnel<\/span><p>169 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2JvdXF1ZXQtYW1vdXItZXhjZXB0aW9ubmVsLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249MUFB\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/3ER-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Ecrin de roses<\/span><p>42.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2VjcmluLWRlLXJvc2VzLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249M0VS\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3RER-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rouge<\/span><p>36.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvdWdlLzAvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249M1JFUg==\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.interflora.fr\/c\/roses-saint-valentin\">Livraison de roses pour la Saint Valentin<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\"><a name=\"huile\"><\/a>L\u2019huile essentielle de rose<\/h2>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:23% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2013\/02\/huile-essentielle-rose.jpg\" alt=\"L'huile de roses\" class=\"wp-image-27559 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>La rose est une des premi\u00e8res senteurs \u00e0 avoir \u00e9t\u00e9 utilis\u00e9e en parfumerie.<\/strong> Les Romains en extrayaient d\u00e9j\u00e0 l\u2019huile essentielle et faisaient une incroyable consommation de roses, notamment pour son parfum. Ses p\u00e9tales remplissaient des coussins, et parfumaient les bains\u2026 Son essence, enivrante et sensuelle, \u00e9tait convi\u00e9e de ce fait aux pr\u00e9paratifs amoureux. On raconte m\u00eame que Cl\u00e9op\u00e2tre et Marc-Antoine pass\u00e8rent leur premi\u00e8re nuit d\u2019amour sur un lit de p\u00e9tales de roses de 45 cm d\u2019\u00e9paisseur&#8230;<\/p>\n\n\n\n<p><strong>La parfumerie utilise principalement la rose de Damas (<em>Rosa damascena<\/em>) et \u00e0 moindre \u00e9chelle la rose cent-feuilles (<em>Rosa centifolia L.<\/em>), appel\u00e9e aussi \u00ab rose de mai \u00bb<\/strong>. Les qualit\u00e9s olfactives de la centifolia de Grasse sont telles qu\u2019on les retrouve chez les grands noms de la parfumerie comme Chanel ou Dior. Cependant, on utilise \u00e0 l\u2019heure actuelle des substituts synth\u00e9tiques, permettant de se passer des huiles essentielles.<\/p>\n\n\n\n<p>L\u2019huile essentielle de rose, ou essence de rose, est obtenue soit par distillation de fleurs fra\u00eechement r\u00e9colt\u00e9es &#8211; proc\u00e9d\u00e9 qui permet d\u2019utiliser le r\u00e9sidu sous forme d\u2019eau de rose &#8211; soit par enfleurage, consistant \u00e0 capter l\u2019essence gr\u00e2ce \u00e0 de la graisse, dont on extraira ensuite la \u00ab concr\u00e8te \u00bb, puis l\u2019 \u00ab&nbsp;absolue&nbsp;\u00bb. L\u2019huile essentielle de rose est particuli\u00e8rement on\u00e9reuse, et pour cause : il faut plus d\u2019une tonne de roses pour en obtenir 100 g !<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>L\u2019essence de rose a des vertus adoucissantes, astringentes, tonifiantes et r\u00e9g\u00e9n\u00e9rantes<\/strong>, c\u2019est pourquoi on la retrouve dans de nombreux produits de beaut\u00e9, notamment des lotions apaisantes et anti-\u00e2ge pour le soin du visage, des mains et des ongles (voir notre article pour vous concocter un masque \u00e0 la rose et retrouver un teint lumineux).<\/p>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>L\u2019huile essentielle de rose peut aussi \u00eatre utilis\u00e9e en pharmacologie, du fait de ses vertus cicatrisantes et h\u00e9mostatiques<\/strong>. Elle aide \u00e0 lutter contre les affections ORL (gingivite, aphte, angine\u2026), les petites br\u00fblures et irritations cutan\u00e9es, les troubles intestinaux et m\u00eame les probl\u00e8mes de libido. Elle peut \u00eatre utilis\u00e9e en massage, dans le bain, en inhalation ou en gargarisme. Demandez conseil \u00e0 un professionnel avant toute utilisation.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><a name=\"langage\"><\/a>La rose dans le langage des fleurs<\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\"><strong>Encens\u00e9e par les po\u00e8tes, la rose est devenue l\u2019all\u00e9gorie de l\u2019amour \u2014 puissant et fragile \u00e0 la fois \u2014, de la fragilit\u00e9 de la vie, de la perfection impossible \u00e0 atteindre mais aussi la personnification-m\u00eame de l\u2019\u00eatre aim\u00e9.<\/strong> Offerte, la rose permet d\u2019exprimer toutes les nuances du sentiment amoureux. Elle poss\u00e8de son propre langage en fonction de sa couleur et de son nombre. D\u00e9couvrir les <a href=\"https:\/\/www.interflora.fr\/blog\/comment-offrir-des-roses\/\">r\u00e8gles \u00e0 conna\u00eetre lorsque vous offrez des roses !<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\" style=\"margin-right:var(--wp--preset--spacing--70);margin-left:var(--wp--preset--spacing--70)\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Le cyclamen : signification et entretien\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zeIVxjeiflo?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.interflora.fr\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\"><a name=\"entretien\"><\/a>Entretien des rosiers<\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">Parmi les principaux types de rosiers, citons :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Les rosiers buissons<\/strong>. Ils regroupent les hybrides de th\u00e9, qui poss\u00e8dent de grandes fleurs doubles et les rosiers buissons, \u00e0 fleurs group\u00e9es (Polyanthas, Floribundas, Grandiflora), portant plusieurs fleurs sur chaque tige. D\u2019une hauteur maximale de 1,50m, ils sont particuli\u00e8rement appr\u00e9ci\u00e9s au jardin en massifs.<\/li>\n\n\n\n<li><strong>Les rosiers arbustifs<\/strong> (ou paysagers). Offrant des fleurs simples, ils peuvent atteindre jusqu\u2019\u00e0 1,80m de hauteur et sont parfaits en sujet isol\u00e9 pour cr\u00e9er des haies fleuries.<\/li>\n\n\n\n<li><strong>Les rosiers couvre-sol<\/strong>. Ils ne d\u00e9passent pas 60 cm de hauteur et s\u2019\u00e9talent sur pr\u00e8s de 2 m. Comme leur nom l\u2019indique, ils d\u00e9corent talus ou plates-bandes.<\/li>\n\n\n\n<li><strong>Les rosiers grimpants<\/strong>. Pouvant atteindre jusqu\u2019\u00e0 6 m de hauteur, ils doivent \u00eatre paliss\u00e9s et d\u00e9coreront \u00e0 merveille pergolas et tonnelles.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-1a2ddb66 wp-block-columns-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Les rosiers aiment la lumi\u00e8re, trouvez-leur une place ensoleill\u00e9e. Si selon le type, des soins sp\u00e9cifiques doivent \u00eatre apport\u00e9s, voici quelques r\u00e8gles de base qui vous aideront \u00e0 prendre soin de vos rosiers.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Arrosage<\/h4>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">Les rosiers ont un atout de taille : ils poss\u00e8dent un syst\u00e8me radiculaire profond. Les rosiers d\u00e9j\u00e0 bien d\u00e9velopp\u00e9s sont ainsi autonomes, et puiseront l\u2019eau dans leur sol. Il faut par contre donner un petit coup de pouce \u00e0 vos rosiers r\u00e9cemment plant\u00e9s, le temps que leurs racines se d\u00e9veloppent. Arrosez ainsi r\u00e9guli\u00e8rement le pied, en \u00e9vitant de mouiller le feuillage. Vous pourrez \u00e9galement pailler le sol afin de maintenir un bon taux d\u2019humidit\u00e9.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00e9sherbage<\/h4>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20);grid-template-columns:auto 26%\"><div class=\"wp-block-media-text__content\">\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">Afin d\u2019\u00e9viter toute contamination, il est vivement conseill\u00e9 de supprimer r\u00e9guli\u00e8rement les mauvaises herbes qui se d\u00e9veloppent au pied de votre rosier. Evitez les d\u00e9sherbants, g\u00e9n\u00e9ralement mal support\u00e9s par les rosiers.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-left\">Binage<\/h4>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--20);padding-left:var(--wp--preset--spacing--20)\">Pensez \u00e0 biner de temps en temps la terre autour du pied entre mars et septembre, afin de permettre une bonne p\u00e9n\u00e9tration de l\u2019eau.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"870\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rosier.jpg\" alt=\"Rosier de roses rouges\" class=\"wp-image-56997 size-full\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rosier.jpg 1000w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rosier-300x261.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/rosier-768x668.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<ul class=\"wp-block-list\">\n<li>La rose est la fleur nationale de nombreux pays : l&rsquo;Angleterre (rose Tudor), la Bulgarie, les Etats-Unis, la Finlande (rose blanche), l&rsquo;Irak, les Maldives, la Roumanie\u2026<\/li>\n\n\n\n<li>La rose se retrouve dans de nombreuses expressions de la langue fran\u00e7aise : \u00ab\u00a0ne pas sentir la rose\u00a0\u00bb (sentir mauvais), \u00ab\u00a0envoyer sur les roses\u00a0\u00bb (\u00e9conduire quelqu&rsquo;un), \u00ab\u00a0d\u00e9couvrir le pot aux roses\u00a0\u00bb (d\u00e9couvrir la v\u00e9rit\u00e9), \u00ab\u00a0\u00e0 l&rsquo;eau de rose\u00a0\u00bb (mi\u00e8vre).<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading alignwide\">Engrais<\/h4>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">L\u2019apport d\u2019engrais est un geste important pour vos rosiers. Choisissez un engrais sp\u00e9cial rosiers que vous utiliserez au moment de la floraison printani\u00e8re, et \u00e0 nouveau en juillet pours les rosiers remontants. R\u00e9pandez l\u2019engrais sur le sol bin\u00e9 et humide. Vous pouvez \u00e9galement entourer le pied de 2 cm d&rsquo;\u00e9paisseur de compost.<\/p>\n\n\n\n<h4 class=\"wp-block-heading alignwide\">Taille<\/h4>\n\n\n\n<p style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">C\u2019est une \u00e9tape capitale pour favoriser de nouvelles floraisons. Supprimez les feuilles mortes, les branches qui pourraient g\u00eaner l\u2019\u00e9closion des fleurs, et celles qui ne produisent pas de fleurs. Conservez les branches les plus vigoureuses. Mais sachez que la taille reste tr\u00e8s sp\u00e9cifique selon le type de rosier. N\u2019h\u00e9sitez pas \u00e0 demander conseil aupr\u00e8s d\u2019un p\u00e9pini\u00e9riste ou d&rsquo;un horticulteur !<\/p>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/04\/3REP-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Composition rose \u00e9ternelle rose<\/span><p>37.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2NvbXBvc2l0aW9uLXJvc2UtZXRlcm5lbGxlLXJvc2UvMC9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj0zUkVQ\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1TEN-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Tendresse<\/span><p>29.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3RlbmRyZXNzZS8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTFURU4=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2026\/01\/1AA-800Wx800H-0-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Amour exceptionnel<\/span><p>169 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2JvdXF1ZXQtYW1vdXItZXhjZXB0aW9ubmVsLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249MUFB\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/1AFO-800Wx800H-0-1-25.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Grandes roses sur-mesure<\/span><p>59.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL3Jvc2VzLWEtbGEtZm9saWUvNi9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj0xQUZP\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons alignwide is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.interflora.fr\/c\/roses-saint-valentin\">Livraison de roses pour la Saint Valentin<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--80);padding-left:var(--wp--preset--spacing--80)\">\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Le langage des fleurs... de A \u00e0 Z\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/KRVIiD_PgoU?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.interflora.fr\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\">&gt;&gt;<a href=\"#haut\"> Retour en haut de page<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Depuis des mill\u00e9naires, la rose fascine. Les artistes ont vu en elle une source d\u2019inspiration in\u00e9puisable au point de la hisser au rang de reine des fleurs&#8230; <\/p>\n","protected":false},"author":11,"featured_media":56998,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[173,167,471],"tags":[344],"class_list":["post-6646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbustes-fleuris","category-ete","category-rose","tag-rosier"],"uagb_featured_image_src":{"full":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores.png",1000,380,false],"thumbnail":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores-150x150.png",150,150,true],"medium":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores-300x114.png",300,114,true],"medium_large":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores-768x292.png",768,292,true],"large":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores.png",1000,380,false],"1536x1536":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores.png",1000,380,false],"2048x2048":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/01\/roses-multicolores.png",1000,380,false]},"uagb_author_info":{"display_name":"Interflora","author_link":"https:\/\/www.interflora.fr\/blog\/author\/lisa\/"},"uagb_comment_info":13,"uagb_excerpt":"Depuis des mill\u00e9naires, la rose fascine. Les artistes ont vu en elle une source d\u2019inspiration in\u00e9puisable au point de la hisser au rang de reine des fleurs...","yoast_meta":{"title":"La rose : symbolique, histoire, entretien des rosiers","description":"La rose est une source d\u2019inspiration in\u00e9puisable, un embl\u00e8me de l\u2019amour absolu, au point d'\u00eatre hiss\u00e9e au rang tr\u00e8s convoit\u00e9 de reine des fleurs."},"_links":{"self":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts\/6646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/comments?post=6646"}],"version-history":[{"count":1,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts\/6646\/revisions"}],"predecessor-version":[{"id":56999,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts\/6646\/revisions\/56999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/media\/56998"}],"wp:attachment":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/media?parent=6646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/categories?post=6646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/tags?post=6646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}