{"id":155,"date":"2025-10-04T16:51:30","date_gmt":"2025-10-04T14:51:30","guid":{"rendered":"https:\/\/www.guide-deuil.com\/?p=155"},"modified":"2025-10-17T12:34:27","modified_gmt":"2025-10-17T10:34:27","slug":"nettoyer-tombe","status":"publish","type":"post","link":"https:\/\/www.interflora.fr\/blog\/nettoyer-tombe\/","title":{"rendered":"Comment nettoyer une tombe et l&rsquo;entretenir correctement"},"content":{"rendered":"\n<p class=\"has-drop-cap\"><strong>Dans de nombreuses cultures, le respect des morts est aussi important que celui des vivants. C\u2019est pourquoi, entretenir une s\u00e9pulture est une marque de respect envers ceux qui nous ont quitt\u00e9s. En plus, il s\u2019agit d\u2019un lieu de recueillement familial, c&rsquo;est pourquoi, il est pr\u00e9f\u00e9rable que la tombe soit gard\u00e9e dans un \u00e9tat convenable, afin que chacun puisse venir s\u2019y recueillir sereinement. N\u00e9anmoins, il n\u2019est pas toujours simple de garder une pierre tombale propre, de fleurir la s\u00e9pulture \u00e0 longueur d\u2019ann\u00e9e et d\u2019\u00e9viter que la mousse ou la rouille n\u2019attaquent la pierre. Il est vrai que les cimeti\u00e8res ne sont pas les lieux que l\u2019on aime le plus visiter, on se contente souvent d\u2019y faire deux ou trois visites par an. C\u2019est pourquoi, il est important d\u2019apprendre comment nettoyer la tombe familiale lors de vos visites. La loi nous oblige-t-elle \u00e0 nettoyer la tombe familiale ? Qu\u2019arrive-t-il \u00e0 la concession si elle est laiss\u00e9e \u00e0 l\u2019abandon ? Quels produits utiliser pour nettoyer le marbre et quelles sont les meilleures techniques pour restaurer les monuments fun\u00e9raires ?<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">En quoi consiste le nettoyage de la tombe ?<\/h2>\n\n\n\n<p>Nettoyer la tombe signifie <strong>rendre la s\u00e9pulture la plus d\u00e9cente qu\u2019il soit<\/strong>. Il y a de nombreux \u00e9l\u00e9ments qui peuvent d\u00e9corer une <a href=\"\/blog\/concession-funeraire\/\" target=\"_blank\" rel=\"noreferrer noopener\">concession<\/a> et chaque tombe est diff\u00e9rente. Qu\u2019il s\u2019agisse d\u2019une tombe recouverte de gazon, de petits cailloux, d\u2019une dalle en marbre ou d\u2019un monument fun\u00e9raire, il faut faire en sorte d\u2019entretenir au mieux ce lieu de comm\u00e9moration. <strong><a href=\"https:\/\/www.interflora.fr\/blog\/un-hommage-fleuri-a-la-toussaint\/\">La Toussaint<\/a><\/strong> est d&rsquo;ailleurs une journ\u00e9e privil\u00e9gi\u00e9e pour l&rsquo;entretien d&rsquo;une tombe Certains ont une pelouse \u00e0 entretenir, d\u2019autres ont d\u2019innombrables plaques en r\u00e9sine \u00e0 r\u00e9curer. Alors que d\u2019autres peuvent se contenter d\u2019un simple brossage sur la <a href=\"\/blog\/choisir-pierre-tombale\/\" target=\"_blank\" rel=\"noreferrer noopener\">pierre tombale<\/a> vieillissante. Voici <strong>quelques astuces<\/strong> qui vont vous permettre d\u2019apprendre comment nettoyer une tombe sans en ab\u00eemer la pierre.<\/p>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6ED-800Wx800H-0-1-12-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6ED-800Wx800H-0-1-12-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6ED-800Wx800H-0-1-12-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6ED-800Wx800H-0-1-12-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6ED-800Wx800H-0-1-12.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Eclat dor\u00e9<\/span><p>89.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLWZsZXVycy1lY2xhdC1kb3JlLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249NkVE\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EE-800Wx800H-0-1-12-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EE-800Wx800H-0-1-12-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EE-800Wx800H-0-1-12-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EE-800Wx800H-0-1-12-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EE-800Wx800H-0-1-12.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Eclosion d&rsquo;espoir<\/span><p>55.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWJvdXF1ZXQtZWNsb3Npb24tZXNwb2lyLzEvRlI\/dXRtX21lZGl1bT1vcmdhbmljJnV0bV9zb3VyY2U9YmxvZ19wcm9kdWN0cyZ1dG1fY2FtcGFpZ249NkVF\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Amiti\u00e9 \u00e9ternelle<\/span><p>59.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLXBsYW50ZXMtYW1pdGllLWV0ZXJuZWxsZS8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTZBRQ==\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Eternelle gratitude et sa bulle d&rsquo;eau<\/span><p>56.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWJvdXF1ZXQtZXRlcm5lbGxlLWdyYXRpdHVkZS1idWxsZS1lYXUvMS9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj02RUdV\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><\/div>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Comment nettoyer la pierre tombale ?<\/h2>\n\n\n\n<p>Le plus souvent, <strong>la pierre tombale est en marbre<\/strong>. Chaque marbre a ses propres qualit\u00e9s et sp\u00e9cificit\u00e9s mais il est tout de m\u00eame choisi pour sa r\u00e9sistance au temps et aux intemp\u00e9ries. Malgr\u00e9 cela, <strong>la pierre vieillit<\/strong> et des salet\u00e9s s\u2019incrustent peu \u00e0 peu, jusqu\u2019\u00e0 ce que cela devienne quasiment impossible d\u2019y rem\u00e9dier. Pourtant, si on sait comment s\u2019y prendre, ce n\u2019est pas si compliqu\u00e9 d\u2019entretenir du marbre ou n\u2019importe quelle autre pierre utilis\u00e9e comme recouvrement pour votre <strong>caveau familial<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Que peut-on utiliser pour nettoyer du marbre ?<\/h2>\n\n\n\n<p>Pour nettoyer une plaque tombale en granit ou en marbre, on vous conseille d\u2019utiliser simplement du <strong>savon noir<\/strong>. Il se peut que les taches soient persistantes, alors pensez \u00e0 acheter un <strong>produit d\u00e9tachant pour sols<\/strong>, comme en utilisent les professionnels. Si vous n\u2019avez pas peur d\u2019astiquer, procurez-vous une <strong>gomme magique<\/strong> et mettez-y quelques gouttes d\u2019eau. Cette solution permet de r\u00e9curer la pierre tombale sans avoir besoin de beaucoup de mat\u00e9riel. Prenez une seconde \u00e9ponge et de l\u2019eau pour rincer et un chiffon pour essuyer. Comme alternative \u00e0 la gomme magique, vous pouvez aussi penser \u00e0 mettre de la <strong>pierre d\u2019argile <\/strong>sur une \u00e9ponge. La pierre d\u2019argile se vend dans le commerce ou peut se fabriquer chez soi, avec du bicarbonate, de l\u2019argile blanche et du liquide vaisselle.<\/p>\n\n\n\n<p>Si le marbre est clair, il est pr\u00e9f\u00e9rable d\u2019utiliser le savon noir et de le frotter \u00e0 l\u2019aide d\u2019une brosse. Apr\u00e8s rin\u00e7age, la plaque de marbre clair reluira. Si vous avez une plaque en marbre sombre ou de couleur, vous pouvez oser utiliser du <strong>blanc de Meudon<\/strong>. Cette craie est souvent utilis\u00e9e pour entretenir des surfaces d\u2019inox, de fa\u00efence ou de verre. Ajoutez une goutte de <strong>t\u00e9r\u00e9benthine<\/strong> \u00e0 l\u2019\u00e9ponge et frottez la pierre.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/pierres-tombales.jpg\" alt=\"\" class=\"wp-image-38914\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Que faire si des taches persistent sur la dalle ?<\/h2>\n\n\n\n<p>Il existe une recette maison qui permet de venir \u00e0 bout des taches les plus tenaces. Avec le temps, le marbre devient plus poreux et des traces de salet\u00e9s s\u2019incrustent dans la pierre. Pour enlever les taches de la pierre tombale en marbre, appliquez une p\u00e2te aux endroits les plus marqu\u00e9s. Cette p\u00e2te est compos\u00e9e d\u2019un <strong>tiers de bicarbonate de soude<\/strong> et de <strong>deux tiers de pierre ponce<\/strong>. Laissez s\u00e9cher la p\u00e2te puis nettoyez la pierre comme indiqu\u00e9 pr\u00e9c\u00e9demment, \u00e0 l\u2019aide d\u2019une \u00e9ponge et de savon noir, avant de rincer.<\/p>\n\n\n\n<p>Les taches de rouille sont aussi fr\u00e9quentes sur le marbre. Pour y venir \u00e0 bout, il suffit d\u2019utiliser un chiffon imbib\u00e9 <strong>d\u2019eau oxyg\u00e9n\u00e9<\/strong>. Diluez l\u2019eau oxyg\u00e9n\u00e9e \u00e0 raison d\u20191 volume pour 20 volumes d\u2019eau. Ensuite rincez et essuyez.<\/p>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Bel hommage blanc<\/span><p>124 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXNzaW4tYmVsLWhvbW1hZ2UtYmxhbmMvMS9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj02QkhX\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Eternelle gratitude et sa bulle d&rsquo;eau<\/span><p>56.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWJvdXF1ZXQtZXRlcm5lbGxlLWdyYXRpdHVkZS1idWxsZS1lYXUvMS9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj02RUdV\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Douce compassion<\/span><p>42.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLXBsYW50ZXMtZG91Y2UtY29tcGFzc2lvbi8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTZEQ08=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6VAW-800Wx800H-0-1-10-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6VAW-800Wx800H-0-1-10-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6VAW-800Wx800H-0-1-10-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6VAW-800Wx800H-0-1-10-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6VAW-800Wx800H-0-1-10.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Voyage astral blanc<\/span><p>139 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLXBsYW50ZXMtdm95YWdlLWFzdHJhbC1ibGFuYy8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTZWQVc=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Livraison rapide<\/p><\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Comment r\u00e9nover la pierre tombale<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Les inscriptions se d\u00e9t\u00e9riorent<\/h3>\n\n\n\n<p>Fr\u00e9quemment, les inscriptions grav\u00e9es dans le marbre s\u2019effacent. Les creux sont normalement peints, afin de mieux faire ressortir les lettres. Mais avec le temps, la peinture s\u2019enl\u00e8ve et les inscriptions deviennent de plus en plus illisibles. Il est d\u2019abord recommand\u00e9 de<strong> gratter la salet\u00e9<\/strong>, par exemple avec un coton-tige tremp\u00e9 dans de l\u2019<strong>ac\u00e9tone ou du White-Spirit<\/strong>. Rincez les lettrages, puis <strong>appliquez une nouvelle couche de peinture<\/strong>. Il existe des peintures pour pierre, \u00e0 appliquer avec un pinceau fin. Parfois un feutre ind\u00e9l\u00e9bile peut suffire. N\u2019oubliez pas de prot\u00e9ger le marbre si vous optez pour une peinture en spray. <strong>Terminez par une couche de vernis<\/strong> incolore pour fixer la couleur et la prot\u00e9ger de l\u2019humidit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le marbre peut \u00eatre prot\u00e9g\u00e9 durablement<\/h3>\n\n\n\n<p>Pour que l\u2019entretien soit plus rapide, il est pr\u00e9f\u00e9rable de <strong>lustrer le marbre<\/strong>. Il s\u2019agit d\u2019une pierre poreuse qui absorbe les taches et la salet\u00e9. Les griffures peuvent aussi se faire assez facilement. C\u2019est pourquoi, il est conseill\u00e9 de prot\u00e9ger la dalle en marbre avec un hydro-ol\u00e9ofuge antitache. Sa texture huileuse prot\u00e9gera durablement la surface. Vous pouvez par exemple frotter votre tombe avec un <strong>chiffon impr\u00e9gn\u00e9 d\u2019huile de lin ou de glyc\u00e9rine<\/strong>. La pierre sera brillante et moins poreuse, donc moins susceptible d\u2019absorber la salet\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/plantes-cimetieres-sans-eau.jpeg\" alt=\"Fleurs et plantes plant\u00e9es devant une pierre tombale\" class=\"wp-image-45489\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Tout ce qu\u2019il faut nettoyer sur la s\u00e9pulture<\/h2>\n\n\n\n<p>La concession ne se limite pas \u00e0 la pierre tombale. Selon les s\u00e9pultures, il peut y avoir une croix en marbre ou une statuette en pierre \u00e0 nettoyer. Autour de la tombe, il y a souvent une bordure. Celle-ci, \u00e0 m\u00eame le sol, est fr\u00e9quemment recouverte de mousse, qu\u2019il ne faut pas oublier de gratter.<\/p>\n\n\n\n<p><strong>Pour d\u00e9corer la tombe<\/strong>, la plupart des familles optent pour des gerbes ou des <strong>bouquets de fleurs<\/strong>. Ceux qui planifient des visites plus rares, choisissent des <strong>fleurs non p\u00e9rissables<\/strong>, c\u2019est-\u00e0-dire, en <strong>plastique<\/strong>. M\u00eame si les fleurs en plastique ne sont pas vivantes, elle ne demandent pas de l\u2019entretien pour autant. Elles jaunissent au soleil, prennent la poussi\u00e8re et moisissent. Il est donc <strong>conseill\u00e9 de les nettoyer elles aussi<\/strong>. Pour nettoyer des fleurs en plastique, il suffit de prendre une \u00e9ponge tremp\u00e9e dans de l\u2019eau dans laquelle on a pr\u00e9alablement vers\u00e9 un peu de <strong>liquide vaisselle<\/strong>. Dans certains cas, vous pouvez m\u00eame utiliser la <strong>pierre d\u2019argile<\/strong> que vous avez prise avec vous pour nettoyer le marbre.<\/p>\n\n\n\n<p>Finalement, on retrouve aussi de nombreuses<strong> plaques comm\u00e9moratives<\/strong> sur les tombes les proches ont laiss\u00e9 des messages. Ces plaques qui ont une grande valeur sentimentale ne demande qu\u2019\u00e0 \u00eatre entretenues. Comme pr\u00e9c\u00e9demment, si elles sont en m\u00e9tal, en marbre ou en r\u00e9sine, vous pouvez utiliser un <strong>m\u00e9lange d\u2019eau et de liquide vaisselle<\/strong>, de la <strong>pierre d\u2019argile<\/strong> ou m\u00eame du produit pour nettoyer les vitres. Si la plaque comm\u00e9morative est en r\u00e9sine, \u00e9vitez d\u2019utiliser des produits abrasifs qui grifferont la plaque ou rendront mat la r\u00e9sine polie. <strong>N\u2019utilisez pas de d\u00e9tergent en poudre, d\u2019eau de Javel, de citron ou de vinaigre<\/strong>. Vous pouvez, encore une fois passer une couche de cire par-dessus, apr\u00e8s avoir nettoy\u00e9 les plaques.<\/p>\n\n\n<div class=\"lp-produits-grid\"><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6BHW-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Bel hommage blanc<\/span><p>124 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXNzaW4tYmVsLWhvbW1hZ2UtYmxhbmMvMS9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj02QkhX\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6AE-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Amiti\u00e9 \u00e9ternelle<\/span><p>59.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLXBsYW50ZXMtYW1pdGllLWV0ZXJuZWxsZS8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTZBRQ==\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Fleurs fra\u00eeches<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6EGU-800Wx800H-0-1-5.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Eternelle gratitude et sa bulle d&rsquo;eau<\/span><p>56.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWJvdXF1ZXQtZXRlcm5lbGxlLWdyYXRpdHVkZS1idWxsZS1lYXUvMS9GUj91dG1fbWVkaXVtPW9yZ2FuaWMmdXRtX3NvdXJjZT1ibG9nX3Byb2R1Y3RzJnV0bV9jYW1wYWlnbj02RUdV\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><div class=\"lp-produit\"><div class=\"lp-thumbnail-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-300x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-300x300.jpg 300w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-150x150.jpg 150w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13-768x768.jpg 768w, https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/05\/6DCO-800Wx800H-0-1-13.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" class=\"lp-badge\" src=\"https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/06\/logo-circle.png\" alt=\"Livraison rapide Interflora\"><\/div><span>Douce compassion<\/span><p>42.95 \u20ac<\/p><span class=\"obf-link lp-cta\" role=\"link\" tabindex=\"0\" data-b64=\"aHR0cHM6Ly93d3cuaW50ZXJmbG9yYS5mci9wL2RldWlsLWNvdXBlLXBsYW50ZXMtZG91Y2UtY29tcGFzc2lvbi8xL0ZSP3V0bV9tZWRpdW09b3JnYW5pYyZ1dG1fc291cmNlPWJsb2dfcHJvZHVjdHMmdXRtX2NhbXBhaWduPTZEQ08=\" data-target=\"_blank\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-bag\" viewBox=\"0 0 16 16\"><path d=\"M8 1a2 2 0 0 1 2 2v1h2.5A1.5 1.5 0 0 1 14 5.5v8A1.5 1.5 0 0 1 12.5 15h-9A1.5 1.5 0 0 1 2 13.5v-8A1.5 1.5 0 0 1 3.5 3H6V2a2 2 0 0 1 2-1zm1 3V3a1 1 0 0 0-2 0v1h2z\"\/><\/svg>Voir le produit<\/span><p class=\"rapido\">Top produit<\/p><\/div><\/div>\n\n\n\n<div style=\"height:18px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide\">Sommes-nous tenus par la loi d\u2019entretenir une tombe ?<\/h2>\n\n\n\n<p>Pour faire simple, non. <strong>Personne ne nous y oblige<\/strong>. D\u2019ailleurs, il serait bien compliqu\u00e9 de savoir qui est la personne d\u00e9sign\u00e9e comme la responsable d\u2019une tombe. Cependant,<strong> une tombe qui est laiss\u00e9e \u00e0 l\u2019abandon risque d\u2019\u00eatre reprise par la commune<\/strong> qui se chargera de la <strong>r\u00e9attribuer \u00e0 une autre famille<\/strong>. Cette d\u00e9cision prend toutefois du temps. En effet, l\u2019article L223-17 pr\u00e9cise que <strong>le maire peut constater l\u2019abandon<\/strong> d\u2019une tombe et l\u2019acter par <strong>proc\u00e8s-verbal<\/strong> d\u00e8s lors que la <strong>s\u00e9pulture n\u2019est plus entretenue pendant 30 ans.<\/strong> Apr\u00e8s plusieurs rappels aux familles et l\u2019affichage d\u2019annonces publiques, le maire et son conseil municipal peuvent, 3 ans apr\u00e8s le premier constat, acter la reprise de la concession par la commune.<\/p>\n\n\n\n<p>L\u2019article R2223-13 vient corroborer le premier article, en ce sens qu\u2019il pr\u00e9cise qu\u2019une tombe ne peut pas \u00eatre consid\u00e9r\u00e9e \u00e0 l\u2019abandon moins de trente ans apr\u00e8s l\u2019acte de concession. Il faut aussi <strong>attendre minimum 10 ans apr\u00e8s la derni\u00e8re inhumation pour conc\u00e9der la s\u00e9pulture \u00e0 la commune<\/strong>.<\/p>\n\n\n\n<p>M\u00eame si la loi ne vous oblige donc pas \u00e0 venir nettoyer la tombe d\u2019une grand-tante que vous n\u2019avez jamais connue, <strong>l\u2019entretien des s\u00e9pultures est un acte civique <\/strong>mais aussi une <strong>marque de respect <\/strong>pour les autres visiteurs du cimeti\u00e8re.<\/p>\n\n\n\n<p><strong>Lire aussi <\/strong>: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"\/blog\/dans-quels-cas-peut-on-demander-une-exhumation-dun-corps\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dans quels cas peut-on demander une exhumation d\u2019un corps ?<\/a><\/li>\n\n\n\n<li><a href=\"\/blog\/cout-cremation-incineration\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cr\u00e9mation : combien co\u00fbte une cr\u00e9mation (ou incin\u00e9ration)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.interflora.fr\/blog\/interdiction-fleurir-une-tombe\/\" target=\"_blank\" rel=\"noreferrer noopener\">Est-il possible d\u2019interdire \u00e0 quelqu\u2019un de fleurir une tombe ?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dans de nombreuses cultures, le respect des morts est aussi important que celui des vivants. C\u2019est pourquoi, entretenir une s\u00e9pulture est une marque de respect envers ceux qui nous ont quitt\u00e9s. En plus, il s\u2019agit d\u2019un lieu de recueillement familial, c&rsquo;est pourquoi, il est pr\u00e9f\u00e9rable que la tombe soit gard\u00e9e dans un \u00e9tat convenable, afin que chacun puisse venir s\u2019y recueillir sereinement.<\/p>\n","protected":false},"author":1,"featured_media":54180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[176,312],"tags":[313],"class_list":["post-155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-toussaint","tag-toussaint"],"uagb_featured_image_src":{"full":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe.jpg",800,450,false],"thumbnail":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe-150x150.jpg",150,150,true],"medium":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe-768x432.jpg",768,432,true],"large":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe.jpg",800,450,false],"1536x1536":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe.jpg",800,450,false],"2048x2048":["https:\/\/www.interflora.fr\/blog\/wp-content\/uploads\/2025\/10\/nettoyer-une-tombe.jpg",800,450,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.interflora.fr\/blog\/author\/admin\/"},"uagb_comment_info":1,"uagb_excerpt":"Dans de nombreuses cultures, le respect des morts est aussi important que celui des vivants. C\u2019est pourquoi, entretenir une s\u00e9pulture est une marque de respect envers ceux qui nous ont quitt\u00e9s. En plus, il s\u2019agit d\u2019un lieu de recueillement familial, c'est pourquoi, il est pr\u00e9f\u00e9rable que la tombe soit gard\u00e9e dans un \u00e9tat convenable, afin\u2026","yoast_meta":{"title":"%%title%% %%page%% | %%sitename%%","description":"Entretenir une s\u00e9pulture est une marque de respect envers ceux qui nous ont quitt\u00e9s. D\u00e9couvrez tous les conseils issus de professionnels."},"_links":{"self":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/comments?post=155"}],"version-history":[{"count":0,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/posts\/155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/media\/54180"}],"wp:attachment":[{"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/categories?post=155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.interflora.fr\/blog\/wp-json\/wp\/v2\/tags?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}